{"id":178,"count":1,"description":"","link":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/","name":"emmeessentials.co","slug":"emmeessentials-co","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des emmeessentials.co - Maison YOKK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des emmeessentials.co - Maison YOKK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison YOKK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/\",\"url\":\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/\",\"name\":\"Archives des emmeessentials.co - Maison YOKK\",\"isPartOf\":{\"@id\":\"https:\/\/yokkfamily.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/yokkfamily.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"emmeessentials.co\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/yokkfamily.com\/#website\",\"url\":\"https:\/\/yokkfamily.com\/\",\"name\":\"Maison YOKK\",\"description\":\"A travers la mode, nous r\u00e9v\u00e9lons l&#039;identit\u00e9 Africaine enfouie en chacun des n\u00f4tres.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/yokkfamily.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des emmeessentials.co - Maison YOKK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des emmeessentials.co - Maison YOKK","og_url":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/","og_site_name":"Maison YOKK","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/","url":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/","name":"Archives des emmeessentials.co - Maison YOKK","isPartOf":{"@id":"https:\/\/yokkfamily.com\/#website"},"breadcrumb":{"@id":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/yokkfamily.com\/index.php\/category\/emmeessentials-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/yokkfamily.com\/"},{"@type":"ListItem","position":2,"name":"emmeessentials.co"}]},{"@type":"WebSite","@id":"https:\/\/yokkfamily.com\/#website","url":"https:\/\/yokkfamily.com\/","name":"Maison YOKK","description":"A travers la mode, nous r\u00e9v\u00e9lons l&#039;identit\u00e9 Africaine enfouie en chacun des n\u00f4tres.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yokkfamily.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/yokkfamily.com\/index.php\/wp-json\/wp\/v2\/categories\/178"}],"collection":[{"href":"https:\/\/yokkfamily.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/yokkfamily.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/yokkfamily.com\/index.php\/wp-json\/wp\/v2\/posts?categories=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}